{"id":1604,"date":"2025-04-16T16:04:18","date_gmt":"2025-04-16T14:04:18","guid":{"rendered":"https:\/\/cjib.cat\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/"},"modified":"2025-04-16T16:04:18","modified_gmt":"2025-04-16T14:04:18","slug":"nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil","status":"publish","type":"post","link":"https:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/","title":{"rendered":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hoy hemos mantenido una reuni\u00f3n con la presidenta del Govern de las Illes Balears para trasladarle un conjunto de propuestas urgentes con el objetivo de hacer frente a la grave situaci\u00f3n que vivimos las personas j\u00f3venes en las Islas. Desde el Consell de la Joventut de les Illes Balears (CJIB) hemos querido poner sobre la mesa una realidad insostenible: el encarecimiento de la vida, el acceso pr\u00e1cticamente imposible a una vivienda digna y un mercado laboral que nos condena a la precariedad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, hemos destacado un dato especialmente alarmante: el salario medio de la juventud en las Islas es un 35% inferior a la media estatal. Esta brecha limita gravemente nuestra autonom\u00eda y condiciones de vida, y exige respuestas inmediatas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, hemos entregado a la presidenta un documento con propuestas concretas, estructuradas en cinco \u00e1mbitos clave:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vivienda:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proponemos que el precio del alquiler no supere el 50% del salario medio juvenil, como medida transitoria hasta alcanzar el 30% que recomiendan organismos internacionales.<\/li>\n\n\n\n<li>Reivindicamos la reducci\u00f3n de impuestos para la compra de la primera vivienda, para favorecer la emancipaci\u00f3n.<\/li>\n\n\n\n<li>Instamos a limitar la adquisici\u00f3n de viviendas a personas que no acrediten una residencia m\u00ednima en las Islas, siguiendo ejemplos de pa\u00edses como Suiza o Dinamarca, para frenar la especulaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transporte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pedimos el aumento de frecuencias, especialmente en la l\u00ednea de metro de la UIB.<\/li>\n\n\n\n<li>Proponemos una tarjeta \u00fanica y digital para el transporte p\u00fablico que funcione en todas las islas.<br><br><\/li>\n\n\n\n<li>Reivindicamos precios asequibles y fijos en vuelos y barcos interinsulares, pensados especialmente para estudiantes que se desplazan entre islas.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabajo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proponemos incentivos fiscales para las empresas que contraten a j\u00f3venes.<\/li>\n\n\n\n<li>Pedimos m\u00e1s recursos para la Inspecci\u00f3n de Trabajo para combatir la explotaci\u00f3n.<\/li>\n\n\n\n<li>Proponemos una cuota joven del 20% en las nuevas contrataciones y una mejora del salario m\u00ednimo juvenil en los convenios colectivos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Apostamos por el etiquetado de advertencia en alimentos poco saludables para fomentar h\u00e1bitos saludables.<\/li>\n\n\n\n<li>Reivindicamos la gratuidad de los anticonceptivos y productos menstruales, para garantizar nuestros derechos sexuales y reproductivos.<\/li>\n\n\n\n<li>Insistimos en la necesidad urgente de reforzar la salud mental p\u00fablica con m\u00e1s psic\u00f3logos y menos listas de espera.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Educaci\u00f3n y lengua:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pedimos que se impartan charlas de educaci\u00f3n sexoafectiva desde los 12 a\u00f1os, centradas en el consentimiento y las buenas pr\u00e1cticas.<\/li>\n\n\n\n<li>Proponemos nuevos grados universitarios en la UIB, como sociolog\u00eda, antropolog\u00eda o ciencias pol\u00edticas.<\/li>\n\n\n\n<li>Reclamamos una mejora real de las delegaciones de la UIB en Menorca, Ibiza y Formentera para garantizar una educaci\u00f3n igualitaria.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este encuentro, volvemos a reafirmar nuestro compromiso como voz colectiva de la juventud de las Islas. Necesitamos pol\u00edticas valientes, estructurales y transversales que pongan fin a la precariedad y garanticen una vida digna para todas las personas j\u00f3venes. Pedimos que se establezca un canal de di\u00e1logo estable y permanente con los representantes juveniles. Solo as\u00ed podremos hacer frente, colectivamente, a los grandes retos del presente y del futuro.   <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-1024x683.jpeg\" alt=\"\" class=\"wp-image-1597\" srcset=\"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-1024x683.jpeg 1024w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-300x200.jpeg 300w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-768x512.jpeg 768w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-1536x1024.jpeg 1536w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern.jpeg 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2-683x1024.jpeg\" alt=\"\" class=\"wp-image-1599\" srcset=\"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2-683x1024.jpeg 683w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2-200x300.jpeg 200w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2-768x1152.jpeg 768w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2-1024x1536.jpeg 1024w, https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg 1066w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hoy hemos mantenido una reuni\u00f3n con la presidenta del Govern de las Illes Balears para trasladarle un conjunto de propuestas urgentes con el objetivo de hacer frente a la grave situaci\u00f3n que vivimos las personas j\u00f3venes en las Islas. Desde el Consell de la Joventut de les Illes Balears (CJIB) hemos querido poner sobre la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears\" \/>\n<meta property=\"og:description\" content=\"Hoy hemos mantenido una reuni\u00f3n con la presidenta del Govern de las Illes Balears para trasladarle un conjunto de propuestas urgentes con el objetivo de hacer frente a la grave situaci\u00f3n que vivimos las personas j\u00f3venes en las Islas. Desde el Consell de la Joventut de les Illes Balears (CJIB) hemos querido poner sobre la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/\" \/>\n<meta property=\"og:site_name\" content=\"Consell de Joventut de les Illes Balears\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T14:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1066\" \/>\n\t<meta property=\"og:image:height\" content=\"1599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/cjib.cat\\\/#\\\/schema\\\/person\\\/0c43ec505932187f4e7fe9847a6baeb4\"},\"headline\":\"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil\",\"datePublished\":\"2025-04-16T14:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cjib.cat\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CJIB-i-Presidencia-Govern-2.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/\",\"url\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/\",\"name\":\"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cjib.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CJIB-i-Presidencia-Govern-2.jpeg\",\"datePublished\":\"2025-04-16T14:04:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CJIB-i-Presidencia-Govern-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/CJIB-i-Presidencia-Govern-2.jpeg\",\"width\":1066,\"height\":1599},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/cjib.cat\\\/es\\\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"http:\\\/\\\/cjib.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cjib.cat\\\/#website\",\"url\":\"https:\\\/\\\/cjib.cat\\\/\",\"name\":\"Consell de Joventut de les Illes Balears\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cjib.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cjib.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cjib.cat\\\/#organization\",\"name\":\"Consell de Joventut de les Illes Balears\",\"url\":\"https:\\\/\\\/cjib.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cjib.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Marca.svg\",\"contentUrl\":\"https:\\\/\\\/cjib.cat\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Marca.svg\",\"width\":255,\"height\":48,\"caption\":\"Consell de Joventut de les Illes Balears\"},\"image\":{\"@id\":\"https:\\\/\\\/cjib.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cjib.cat\\\/#\\\/schema\\\/person\\\/0c43ec505932187f4e7fe9847a6baeb4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/cjib.cat\"],\"url\":\"https:\\\/\\\/cjib.cat\\\/es\\\/author\\\/4kd8ec_nedb2sst\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/","og_locale":"es_ES","og_type":"article","og_title":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears","og_description":"Hoy hemos mantenido una reuni\u00f3n con la presidenta del Govern de las Illes Balears para trasladarle un conjunto de propuestas urgentes con el objetivo de hacer frente a la grave situaci\u00f3n que vivimos las personas j\u00f3venes en las Islas. Desde el Consell de la Joventut de les Illes Balears (CJIB) hemos querido poner sobre la [&hellip;]","og_url":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/","og_site_name":"Consell de Joventut de les Illes Balears","article_published_time":"2025-04-16T14:04:18+00:00","og_image":[{"width":1066,"height":1599,"url":"http:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#article","isPartOf":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/"},"author":{"name":"admin","@id":"https:\/\/cjib.cat\/#\/schema\/person\/0c43ec505932187f4e7fe9847a6baeb4"},"headline":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil","datePublished":"2025-04-16T14:04:18+00:00","mainEntityOfPage":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/cjib.cat\/#organization"},"image":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#primaryimage"},"thumbnailUrl":"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/","url":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/","name":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil - Consell de Joventut de les Illes Balears","isPartOf":{"@id":"https:\/\/cjib.cat\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#primaryimage"},"image":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#primaryimage"},"thumbnailUrl":"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg","datePublished":"2025-04-16T14:04:18+00:00","breadcrumb":{"@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#primaryimage","url":"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg","contentUrl":"https:\/\/cjib.cat\/wp-content\/uploads\/2025\/04\/CJIB-i-Presidencia-Govern-2.jpeg","width":1066,"height":1599},{"@type":"BreadcrumbList","@id":"http:\/\/cjib.cat\/es\/nos-reunimos-con-la-presidenta-del-govern-para-reclamar-medidas-valientes-ante-la-precariedad-juvenil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"http:\/\/cjib.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Nos reunimos con la presidenta del Govern para reclamar medidas valientes ante la precariedad juvenil"}]},{"@type":"WebSite","@id":"https:\/\/cjib.cat\/#website","url":"https:\/\/cjib.cat\/","name":"Consell de Joventut de les Illes Balears","description":"","publisher":{"@id":"https:\/\/cjib.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cjib.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cjib.cat\/#organization","name":"Consell de Joventut de les Illes Balears","url":"https:\/\/cjib.cat\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cjib.cat\/#\/schema\/logo\/image\/","url":"https:\/\/cjib.cat\/wp-content\/uploads\/2024\/06\/Marca.svg","contentUrl":"https:\/\/cjib.cat\/wp-content\/uploads\/2024\/06\/Marca.svg","width":255,"height":48,"caption":"Consell de Joventut de les Illes Balears"},"image":{"@id":"https:\/\/cjib.cat\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cjib.cat\/#\/schema\/person\/0c43ec505932187f4e7fe9847a6baeb4","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc3698a81f00fcd1bcb069c5a9bb6000c98bd8da5d5981e2bdd4b19196ac0c3a?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/cjib.cat"],"url":"https:\/\/cjib.cat\/es\/author\/4kd8ec_nedb2sst\/"}]}},"_links":{"self":[{"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/posts\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/comments?post=1604"}],"version-history":[{"count":0,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/posts\/1604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/media\/1600"}],"wp:attachment":[{"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/media?parent=1604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/categories?post=1604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cjib.cat\/es\/wp-json\/wp\/v2\/tags?post=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}